{"id":1603,"date":"2012-05-05T00:25:00","date_gmt":"2012-05-04T22:25:00","guid":{"rendered":"https:\/\/www.africavenir.com\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/"},"modified":"2023-10-06T11:40:56","modified_gmt":"2023-10-06T09:40:56","slug":"pr-issa-ndiaye-mali-une-democratie-contre-le-peuple","status":"publish","type":"post","link":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/","title":{"rendered":"Pr Issa N\u2019Diaye: Mali &#8211; une \u2018d\u00e9mocratie\u2019 contre le peuple !"},"content":{"rendered":"<p>La chute brutale de ATT a mis \u00e0 nu les fondements pourris de la d\u00e9mocratie malienne tant chant\u00e9e \u00e0 l\u2019ext\u00e9rieur. Les populations maliennes l\u2019avaient compris il y a belle lurette. En t\u00e9moignent les taux de participation qui d\u00e9gringolaient d\u2019\u00e9lection en \u00e9lection. De 1991 \u00e0 nos jours, \u00e0 peine 20% des Maliens participent r\u00e9guli\u00e8rement aux \u00e9lections. Depuis deux d\u00e9cennies, nous avons l\u2019un des taux de participation aux \u00e9lections les plus bas en Afrique. Peut-on honn\u00eatement dans ces conditions qualifier de l\u00e9gitime une \u2018d\u00e9mocratie\u2019 autant boud\u00e9e par son propre peuple?nLe coup d\u2019Etat du 22 mars 2012 a soulev\u00e9 un concert de condamnations plus ou moins sinc\u00e8res. Certains l\u2019ont condamn\u00e9, parce qu\u2019ils n\u2019\u00e9taient pas objectivement inform\u00e9s des r\u00e9alit\u00e9s maliennes, victimes na\u00effs de la propagande orchestr\u00e9e par le r\u00e9gime et ses soutiens ext\u00e9rieurs. Parmi eux des d\u00e9mocrates sinc\u00e8res qui, par conviction, n\u2019ont jamais adh\u00e9r\u00e9 aux coups d\u2019Etat militaires intervenus depuis la vague des ind\u00e9pendances africaines, coups d\u2019Etat la plupart du temps inspir\u00e9s et soutenus par les pays occidentaux et parmi eux surtout la France dans ses anciennes possessions coloniales. Depuis rien n\u2019a fondamentalement chang\u00e9 sinon les m\u00e9thodes devenues plus subtiles pour transformer des dictatures militaires en r\u00e9gimes \u2018d\u00e9mocratiques\u2019 par la magie du bulletin de vote lors d\u2019\u00e9lections visiblement tronqu\u00e9es mais valid\u00e9es avec le concours d\u2019observateurs internationaux offrant complaisamment un certificat d\u2019authenticit\u00e9 \u00e0 un processus \u00e9lectoral auquel n\u2019adh\u00e8rent point les populations directement concern\u00e9es. Lors des derni\u00e8res \u00e9lections au Mali, l\u2019ancien Pr\u00e9sident de la cour constitutionnelle&nbsp; a eu&nbsp; \u00e0 dire qu\u2019il n\u2019y avait jamais eu autant de fraudes et d\u2019irr\u00e9gularit\u00e9s! Pourtant les r\u00e9sultats \u00e9lectoraux obtinrent le label d\u00e9mocratique. Cependant les Maliennes et les Maliens n\u2019ont jamais eu autant de m\u00e9pris pour leurs dirigeants et leur classe politique. Aujourd\u2019hui les langues commencent \u00e0 se d\u00e9lier r\u00e9v\u00e9lant toute la puanteur d\u2019un syst\u00e8me bas\u00e9 sur le mensonge et le pillage des ressources publiques par une minorit\u00e9 de brigands en uniforme et en col blanc.nQuoi de plus normal qu\u2019on s\u2019\u00e9poumone alors contre le coup d\u2019Etat. Suffit-il de condamner un coup d\u2019Etat pour \u00eatre un d\u00e9mocrate alors que sa pratique quotidienne du pouvoir et de la gestion des affaires publiques est un d\u00e9ni de d\u00e9mocratie ? Est-on r\u00e9ellement d\u00e9mocrate quand on est aux c\u00f4t\u00e9s des dictateurs \u2018d\u00e9mocratiquement\u2019 \u00e9lus contre leur propre peuple ? Est-on r\u00e9ellement d\u00e9mocrate quand, deux d\u00e9cennies durant, la pratique \u2018d\u00e9mocratique\u2019 du pouvoir a plong\u00e9 les populations maliennes dans les affres de la mis\u00e8re, de l\u2019injustice et de l\u2019impunit\u00e9. Est-ce d\u00e9mocratique que de l\u2019\u00e9tranger on vienne restaurer un ordre constitutionnel dont ne veut plus visiblement un peuple ? Est-il d\u00e9mocratique d\u2019imposer la d\u00e9mocratie \u00e0 coups d\u2019intervention militaire et de menaces en tous genres ? De quelle d\u00e9mocratie s\u2019agit-il ? D\u00e9mocratie de la mis\u00e8re pour le plus grand nombre, d\u00e9mocratie des millionnaires et milliardaires pour une \u00e9lite qui a tout vol\u00e9 et accapar\u00e9 ?<br \/>Que dire aussi des r\u00e9gimes \u2018d\u00e9mocratiques\u2019 africains surtout dans l\u2019espace francophone? Bien de putschistes d\u2019hier sont devenus aujourd\u2019hui des \u2018d\u00e9mocrates\u2019 l\u00e9gitim\u00e9s par des coups d\u2019Etat \u00e9lectoraux. Les dirigeants occidentaux s\u2019en sont-ils offusqu\u00e9s ? Ils les re\u00e7oivent \u00e0 leur table, trinquent avec eux en toute amiti\u00e9. Ils continuent \u00e0 coop\u00e9rer, \u00e0 soutenir des r\u00e9gimes dont les mains sont rougies du sang de leur peuple.&nbsp;nEt curieusement l\u2019on constate surtout dans l\u2019espace francophone en Afrique que partout o\u00f9 gouvernent des r\u00e9gimes militaires d\u00e9guis\u00e9s en d\u00e9mocratie, point n\u2019est besoin de bases militaires fran\u00e7aises. Ils font proprement le boulot qui leur est demand\u00e9. Par contre l\u00e0 o\u00f9 des civils sont au pouvoir, les ba\u00efonnettes fran\u00e7aises assurent leurs arri\u00e8res. Si l\u2019Afrique est malade des ses dictatures militaires \u2018d\u00e9mocratis\u00e9es\u2019 et de sa classe politique apatride et rapace, elle l\u2019est aussi et principalement de l\u2019interventionnisme des occidentaux qui d\u00e9signent en fait nos dirigeants \u00e0 travers des processus \u00e9lectoraux arrang\u00e9s \u00e0 l\u2019avance. C\u2019est \u00e0 juste raison que les peuples ont choisi jusqu\u2019ici de leur tourner le dos. Mais cela suffit-il d\u00e9sormais ? Faut-il baisser les bras et s\u2019en remettre \u00e0 des coups d\u2019Etat \u2018sauveurs\u2019 comme celui du 22 mars au Mali?nLa guerre au nord Mali n\u2019est point une surprise. Elle est la cons\u00e9quence d\u2019enjeux g\u00e9opolitiques et g\u00e9ostrat\u00e9giques autour du p\u00e9trole, du gaz, de l\u2019uranium, de l\u2019eau, du fer, du mangan\u00e8se, du cuivre, du charbon, du thorium et autres m\u00e9taux pr\u00e9cieux, des trafics d\u2019armes et de drogue et autres motifs inavou\u00e9s et inavouables qui renflouent les caisses d\u2019une Europe menac\u00e9e par la faillite de l\u2019euro et un monde ballot\u00e9 par la crise financi\u00e8re. Le MNLA, les djihadistes et autres acteurs, les r\u00e9gimes militaro-civils \u2018d\u00e9mocratiquement \u00e9lus\u2019 ne sont que les bras arm\u00e9s des vis\u00e9es de certaines multinationales occidentales et de p\u00e9tromonarchies du golfe arabique. Tous sont en r\u00e9alit\u00e9 manipul\u00e9s dans une guerre impos\u00e9e \u00e0 nos populations multiethniques qui ont v\u00e9cu en intelligence des si\u00e8cles durant. En t\u00e9moigne le vieux projet fran\u00e7ais d\u2019OCRS (Organisation Commune des R\u00e9gions Sahariennes : une superficie environ 15 fois plus grande que la France) datant de la colonisation et toujours d\u2019actualit\u00e9 dans certains milieux nostalgiques occidentaux. C\u2019est la colonisation europ\u00e9enne qui a divis\u00e9 et jet\u00e9 les unes contre les autres des populations que nos empires avaient su brasser pour construire des nations cosmopolites.&nbsp;<br \/>La rapidit\u00e9 de la victoire des rebelles touaregs ne saurait \u00eatre simplement justifi\u00e9e par la sup\u00e9riorit\u00e9 de leur armement fourni en partie par la France et le Qatar et livr\u00e9 via la Mauritanie, l\u2019assistance tactique offerte par certains pays, l\u2019audace et la bravoure de leurs troupes. Elle s\u2019explique aussi et largement, par le travail de sape interne accompli au plus haut sommet de l\u2019Etat par ATT et ses complices militaires et civils, traitres \u00e0 leur propre patrie. Aujourd\u2019hui bien de sombres histoires remontent jusque sur la place publique. Les jours&nbsp; prochains l\u00e8veront bien de voiles et sur bien de choses, sur les fortunes colossales et subites de bien de politiciens. Le peuple en sortira encore plus meurtri par tant de trahisons et de bassesses de la part de ses dirigeants aussi bien militaires que civils.&nbsp;nFace \u00e0 cette guerre impos\u00e9e, partout se l\u00e8vent des volontaires d\u00e9sireux de participer \u00e0 la lutte de r\u00e9sistance patriotique pour recouvrer la dignit\u00e9 perdue et r\u00e9tablir l\u2019unit\u00e9 nationale et l\u2019int\u00e9grit\u00e9 territoriale du pays. Ils ne veulent point d\u2019intervention ext\u00e9rieure ni de forces d\u2019interposition de la CEDEAO. Ils savent que derri\u00e8re la r\u00e9bellion et la CEDEAO, se cache la France et d\u2019autres puissances. Pour eux, ceux qui pr\u00f4nent la n\u00e9gociation, rien que la n\u00e9gociation, sont les partisans de la partition de fait du pays. La chute de Gao et de Tombouctou a cr\u00e9\u00e9 un \u00e9tat de choc violent dans la conscience des populations. Elle a remis au go\u00fbt du jour le vieux projet colonial fran\u00e7ais de l\u2019OCRS. La brutalit\u00e9 et l\u2019arrogance de la bande Sarkozy-Jupp\u00e9 et Compagnie, leur accompagnement tout aussi brutal et arrogant par la CEDEAO ont r\u00e9veill\u00e9 le nationalisme malien. Les Maliens savent aujourd\u2019hui que la France de Sarkozy n\u2019est point leur amie. Cependant ils ne font point l\u2019amalgame entre le peuple fran\u00e7ais et ses dirigeants actuels. De nombreux fran\u00e7ais, des hommes politiques fran\u00e7ais de gauche, de nombreuses associations fran\u00e7aises t\u00e9moignent quotidiennement leur solidarit\u00e9 avec le peuple malien.nQue dire aussi des pays africains, notamment ceux de la CEDEAO et surtout des voisins imm\u00e9diats du Mali ?nLes Maliens comprennent difficilement&nbsp; l\u2019attitude de l\u2019Alg\u00e9rie. Gao et Tombouctou ont servi longtemps de base arri\u00e8re \u00e0 la lutte d\u2019ind\u00e9pendance du peuple alg\u00e9rien. Son pr\u00e9sident actuel en sait personnellement quelque chose. M\u00eame si les voltes-faces et les trahisons multiples de ATT ont effarouch\u00e9 bon nombre de pays voisins, cela ne peut en aucun cas justifier l\u2019indiff\u00e9rence voire la complicit\u00e9 alg\u00e9rienne de fait avec la r\u00e9bellion touar\u00e8gue. L\u2019enl\u00e8vement de ses diplomates \u00e0 Gao pourrait \u00eatre l\u2019occasion d\u2019un r\u00e9examen de sa position. Face aux convoitises internationales, le salut du Mali passe par la construction d\u2019un axe strat\u00e9gique avec l\u2019Alg\u00e9rie. Elle est et restera une alli\u00e9e incontournable malgr\u00e9 les m\u00e9fiances et d\u00e9chirures actuelles.nL\u2019attitude de la Mauritanie n\u2019a gu\u00e8re surpris non plus. Elle abrite l\u2019une des repr\u00e9sentations officielles de la r\u00e9bellion. Tout le monde sait ce que doit l\u2019actuel pr\u00e9sident mauritanien \u00e0 la France de Sarkozy. La Mauritanie est devenue un des bras arm\u00e9s de la France dans la r\u00e9gion. Ses exp\u00e9ditions guerri\u00e8res successives en territoire malien avec parfois des massacres de populations civiles innocentes pr\u00e9sent\u00e9es \u00e0 tort comme \u00e9tant des terroristes, ont indign\u00e9 de nombreux Maliens r\u00e9volt\u00e9s par l\u2019indiff\u00e9rence et la complicit\u00e9 de ATT et de ses g\u00e9n\u00e9raux. De nombreux soldats du retour du front racontent abondamment les nombreux coups de poignard dans le dos port\u00e9s par ATT et sa clique d\u2019officiers sup\u00e9rieurs, leurs trahisons et forfaitures. Jamais un peuple n\u2019a \u00e9t\u00e9 autant trahi par ses dirigeants.nQuant \u00e0 la C\u00f4te d\u2019Ivoire de Alassane Ouattara, elle a soulev\u00e9 une immense d\u00e9ception dans l\u2019inconscient collectif des Maliens. Beaucoup d\u2019entre eux ont laiss\u00e9 leur vie et leurs biens dans les affrontements mortels entre Ouattara et Gbagbo. Dans leur immense majorit\u00e9, ils ont pris fait et cause pour Ouattara. Ils ont spontan\u00e9ment et volontairement port\u00e9 assistance \u00e0 leurs fr\u00e8res ivoiriens en difficult\u00e9. Ils ne comprennent et n\u2019acceptent aucunement tant d\u2019ingratitude de la part d\u2019un homme qu\u2019ils ont port\u00e9 dans leur c\u0153ur. Comment comprendre son acharnement contre tout un peuple qu\u2019on a voulu punir pour un seul individu, pour ATT, pour un homme qui a trahi son pays ? Les sanctions d\u00e9cid\u00e9es par le CEDEAO ont bris\u00e9 leur foi dans la solidarit\u00e9 africaine. Le panafricanisme qui avait jusque l\u00e0 fa\u00e7onn\u00e9 leur vision de l\u2019unit\u00e9 africaine a vol\u00e9 en \u00e9clat. La C\u00f4te d\u2019Ivoire est fortement per\u00e7ue comme l\u2019instrument docile de la France.&nbsp;nEn ce qui concerne le Burkina, la m\u00e9fiance reste de mise. Pour bon nombre des Maliens, il a toujours abrit\u00e9 des bases arri\u00e8res de la r\u00e9bellion touar\u00e8gue. Dieu seul sait les sombres arri\u00e8res pens\u00e9es de son pr\u00e9sident Blaise Compraor\u00e9 et ses desseins funestes pour le Mali. Peut-on \u00eatre m\u00e9diateur si l\u2019on n\u2019a pas de complicit\u00e9 avec les uns ou avec les autres ? L\u2019opportunisme burkinab\u00e9 est souvent consid\u00e9r\u00e9 comme de la duplicit\u00e9. Sa collusion avec la politique fran\u00e7aise en Afrique ne fait gu\u00e8re de doute.nSi la non application imm\u00e9diate des sanctions de la CEDEAO par le S\u00e9n\u00e9gal a soulev\u00e9 une certaine sympathie vis-\u00e0-vis de son nouveau pr\u00e9sident, les Maliens n\u2019ont point compris pourquoi et comment un ministre fran\u00e7ais ait pu participer \u00e0 un sommet de chefs d\u2019Etat africains pouss\u00e9s \u00e0 prendre des d\u00e9cisions fondamentalement injustes et dirig\u00e9s contre des victimes innocentes.nComment a-t-on pu se pr\u00e9occuper du seul sort d\u2019ATT et de ses complices et faire peu de cas de celui de tout un peuple ? Pourtant la mauvaise gestion, la corruption, les d\u00e9tournements massifs des deniers publics, l\u2019impunit\u00e9, l\u2019arrogance des auteurs de ces forfaits&nbsp; sont connus de tous. La d\u00e9mocratie est-elle impunit\u00e9 ? Pourquoi prot\u00e9ger des voleurs et leur permettre d\u2019\u00e9chapper ainsi \u00e0 la justice de leur pays? Les populations veulent que rendent compte et soient punis ceux qui les ont pill\u00e9es au nom de la d\u00e9mocratie.nAujourd\u2019hui le divorce entre le Mali et ses voisins est largement consomm\u00e9. Le seul r\u00e9confort est venu de la&nbsp; retenue du Niger et des manifestations de soutien des populations. La prise de position ferme du Niger quant \u00e0 la n\u00e9cessit\u00e9 d\u2019une offensive militaire pour cr\u00e9er un rapport de force favorable sur le terrain susceptible d\u2019obliger les rebelles \u00e0 une n\u00e9gociation sans illusion, a \u00e9t\u00e9 comme un baume sur les plaies b\u00e9antes d\u2019un peuple meurtri par la trahison de ses dirigeants et de la plupart de ses voisins imm\u00e9diats. Cependant les marches de soutien, les nombreux t\u00e9moignages de soutien populaire \u00e0 Bouak\u00e9, Ouagadougou, Niamey et Conakry et ailleurs ont \u00e9t\u00e9&nbsp; fortement appr\u00e9ci\u00e9s. Une v\u00e9rit\u00e9 a surgi dans la conscience collective des Maliens, celle d\u2019une CEDEAO des dirigeants africains au service des int\u00e9r\u00eats fran\u00e7ais et \u00e9trangers contre leurs propres peuples.&nbsp;nLa seconde d\u00e9chirure profonde qui est apparue dans la conscience collective des populations maliennes est le rejet violent de sa classe politique au pouvoir depuis bient\u00f4t deux d\u00e9cennies pour certains. Sa promptitude \u00e0 d\u00e9noncer le coup d\u2019Etat et son concert de d\u00e9nonciations r\u00e9clamant \u00e0 cors et \u00e0 cris le r\u00e9tablissement rapide de l\u2019ordre constitutionnel ancien qui consacrait sa domination, son appel muscl\u00e9 pour une intervention arm\u00e9e \u00e9trang\u00e8re les ont r\u00e9volt\u00e9es. La guerre dans le nord du Mali, les populations brutalement jet\u00e9es sur les routes de l\u2019exil, les massacres, les viols et destructions de biens, le d\u00e9sarroi de tout un peuple ne faisaient point partie des&nbsp; pr\u00e9occupations des politiciens. Seul leur importaient leur avenir personnel, inquiets qu\u2019ils sont de l\u2019interruption brutale de leur festin par le coup d\u2019Etat du 22 mars. Ils continuaient \u00e0 r\u00e9clamer co\u00fbte que co\u00fbte des \u00e9lections alors qu\u2019ils savaient pertinemment que le pays \u00e9tait d\u00e9j\u00e0 entr\u00e9 en guerre et que la pr\u00e9paration mat\u00e9rielle des \u00e9lections \u00e9tait largement insuffisante et \u00e0 dessein.&nbsp;nChacun d\u2019eux \u00e9tait convaincu de l\u2019emporter en raison des milliards vol\u00e9s au peuple avec lesquels ils comptaient acheter le vote de ceux qui \u00e9taient dispos\u00e9s \u00e0 vendre leurs voix, les machines \u00e0 tricher qu\u2019ils avaient invent\u00e9es et le concours des f\u00e9ticheurs et charlatans en tous genres qui avaient pr\u00e9dit leur victoire in\u00e9vitable. Le pouvoir et sa jouissance absolue \u00e9taient \u00e0 port\u00e9e de main. Ils n\u2019avaient jamais compris qu\u2019il \u00e9tait d\u00e9j\u00e0 \u00e0 terre et dans la rue. Il fut soulev\u00e9 par les semelles des soldats de Kati r\u00e9volt\u00e9s et \u00e9c\u0153ur\u00e9s, qui dans leur marche improvis\u00e9e sur le palais de Koulouba, n\u2019eurent m\u00eame pas \u00e0 se baisser pour le ramasser devant la fuite honteuse du G\u00e9n\u00e9ral ATT qui clamait partout conna\u00eetre la guerre et qui d\u00fbt fuir \u00e0 travers rocailles et broussailles de la colline de Koulouba et se mettre honteusement sous protection \u00e9trang\u00e8re. Sa fuite nocturne \u00e0 bord de l\u2019avion pr\u00e9sidentiel s\u00e9n\u00e9galais fut salu\u00e9e par une pluie d\u2019injures, de crachats et de quolibets de la part de soldats \u00e9c\u0153ur\u00e9s par tant de f\u00e9lonie. Triste fin empreinte de l\u00e2chet\u00e9 de la part d\u2019un traitre us\u00e9 et min\u00e9 par ses propres roublardises. L\u2019histoire le traitera sans complaisance aucune.<br \/>Mais comment analyser et comprendre le d\u00e9sastre actuel au del\u00e0 des \u00e9v\u00e8nements actuels ?nLa faille essentielle de l\u2019accord r\u00e9alis\u00e9 entre la junte militaire et la CEDEAO est qu\u2019elle se contente uniquement de r\u00e9aliser un compromis entre les militaires et la classe politique spoli\u00e9e de la jouissance du pouvoir par le coup d\u2019Etat. Ledit accord ne se pr\u00e9occupe nullement du sort du peuple malien<br \/>Le peuple est largement absent de l\u2019accord cadre avec la CEDEAO qui ne tient nullement compte de l\u2019aspiration profonde des Maliennes et des Maliens au changement. Le coup d\u2019Etat a soulev\u00e9 d\u2019immenses esp\u00e9rances dans leur t\u00eate, l\u2019espoir de la fin de leur calvaire, la fin d\u2019une d\u00e9mocratie maffieuse pour laquelle ils n\u2019ont que m\u00e9pris. La coupure est d\u00e9sormais nette entre le camp des restaurateurs de l\u2019ordre ancien et celui des patriotes favorables au changement. Malgr\u00e9 la campagne massive en faveur des premiers des medias occidentaux notamment RFI et France 24 qui refusent de couvrir les manifestations populaires saluant le coup d\u2019Etat, ils restent largement isol\u00e9s, point\u00e9s du doigt dans leur complicit\u00e9 active et totale avec ATT. La ligne de d\u00e9marcation n\u2019est plus entre anti putschiste et putschiste mais d\u00e9sormais entre apatride et patriote, entre ennemis et amis du peuple.nLa population malienne dans sa grande majorit\u00e9 est dans le camp du changement. Elle est fatigu\u00e9e de cette classe politique qui l\u2019a pressuris\u00e9e et qui s\u2019est copieusement enrichie battant tous les records de la corruption en Afrique.<br \/>La d\u00e9mocratie malienne est porteuse d\u2019un p\u00e9ch\u00e9 originel, celui du contexte dans lequel elle est n\u00e9e.nLa chute de la dictature de Moussa Traor\u00e9 n\u2019a nullement entrain\u00e9 celle du syst\u00e8me d\u2019Etat en place. Les nouveaux dirigeants se sont coul\u00e9s dans une machine d\u2019Etat fondamentalement antid\u00e9mocratique qui&nbsp; a fini par les happer. En outre, ils n\u2019ont pas su faire \u00e9merger une nouvelle race de fonctionnaires et d\u2019agents de l\u2019Etat susceptibles d\u2019en faire une machine au service de l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral. Le client\u00e9lisme politique et le n\u00e9potisme ont favoris\u00e9 l\u2019\u00e9mergence d\u2019une caste de bureaucrates opportunistes, dociles et incomp\u00e9tents qui finirent par d\u00e9cr\u00e9dibiliser et d\u00e9truire l\u2019Etat pour le mettre exclusivement au service d\u2019int\u00e9r\u00eats individuels et priv\u00e9s. De Alpha Oumar Konar\u00e9 \u00e0 ATT&nbsp; la machine s\u2019emballa jusqu\u2019\u00e0 l\u2019explosion. La d\u00e9route brutale de l\u2019arm\u00e9e malienne n\u2019en est que l\u2019un des signes distinctifs. On ne saurait r\u00e9soudre les probl\u00e8mes actuels sans analyser et trouver une r\u00e9ponse courageuse \u00e0 la question de la n\u00e9cessaire restructuration de l\u2019Etat et de son assainissement, la refondation de la d\u00e9mocratie malienne, des questions qui ne sont nullement inscrites \u00e0 l\u2019ordre du jour de la CEDEAO et de ses tuteurs internationaux ni dans l\u2019agenda de la classe politique malienne qui n\u2019en veut pas visiblement et pour cause !&nbsp;nLa d\u00e9mocratie malienne est malade de la culture de parti unique dont elle a h\u00e9rit\u00e9e de l\u2019UDPM, ancien parti unique de Moussa Traor\u00e9. Le multipartisme int\u00e9gral consacr\u00e9 par l\u2019\u00e8re \u2018d\u00e9mocratique\u2019 a, en r\u00e9alit\u00e9, donn\u00e9 naissance \u00e0 une multitude de \u2018partis uniques\u2019, sans vie d\u00e9mocratique interne, sans d\u00e9bat interne, sans&nbsp; alternance en son sein. Les partis sont devenus la propri\u00e9t\u00e9 de leurs dirigeants qui sont rest\u00e9s les m\u00eames, la caisse de r\u00e9sonance de leurs ambitions individuelles. Aucun v\u00e9ritable projet de soci\u00e9t\u00e9, aucun programme de gouvernement, aucune identit\u00e9 id\u00e9ologique sinon une ru\u00e9e vers la majorit\u00e9 pr\u00e9sidentielle en vue de profiter des avantages du pouvoir. Dire non et accepter d\u2019aller \u00e0 l\u2019opposition,&nbsp; \u00e0 quelques rares exceptions pr\u00e8s, n\u2019est gu\u00e8re envisageable pour ces \u2018pouvoiristes\u2019 d\u2019un genre nouveau, press\u00e9s qu\u2019ils sont, d\u2019aller s\u2019asseoir \u00e0 la table du festin du pouvoir. La d\u00e9mocratie fut un v\u00e9ritable festival de brigands \u00e0 un point tel que le peuple devint nostalgique de la dictature. Vouloir retourner \u00e0 de telles institutions autant vomies par&nbsp; le peuple, est-ce de la d\u00e9mocratie ?nEn l\u2019espace d\u2019un mois, le peuple malien a re\u00e7u plusieurs gifles retentissantes qu\u2019il n\u2019oubliera pas de si t\u00f4t. Elles furent v\u00e9cues comme une grande humiliation de la part d\u2019un peuple si fier de par son histoire.nLa d\u00e9route de son arm\u00e9e et surtout la fa\u00e7on ridicule dont elle s\u2019est transform\u00e9e en d\u00e9bandade, porta un rude coup \u00e0 sa fiert\u00e9 et \u00e0 sa dignit\u00e9. Les replis dits tactiques successifs, l\u2019abandon des positions sans combat avec armes et minutions, ont durablement bris\u00e9 la confiance en&nbsp; l\u2019arm\u00e9e nationale. Les d\u00e9clarations quant \u00e0 la sup\u00e9riorit\u00e9 de l\u2019armement ennemi ne sauraient justifier le manque de combativit\u00e9 des militaires. La pl\u00e9thore d\u2019officiers, de g\u00e9n\u00e9raux, de colonels et chefs de bataillons, leur train de vie, leur affairisme connue de tous, en disaient long sur leur capacit\u00e9 \u00e0 conduire les troupes au combat.&nbsp;nL\u2019effondrement de l\u2019arm\u00e9e fit comprendre \u00e0 tous celui de l\u2019Etat lui-m\u00eame.nLa seconde humiliation fut celle des sanctions de la CEDEAO, l\u2019arrogance avec laquelle elle fut annonc\u00e9e par les pr\u00e9sidents b\u00e9ninois et ivoiriens. Les Maliens \u00e9taient pr\u00eats \u00e0 en relever les d\u00e9fis. Ils furent bless\u00e9s de nouveau dans leur dignit\u00e9 par la reculade tout aussi brutale du CNRDRE, un autre repli tactique sans doute ! Le forcing des envoy\u00e9s burkinab\u00e9 et ivoirien, les accords sign\u00e9s par les militaires sous leur dict\u00e9e aggrav\u00e8rent le d\u00e9sarroi des populations.<br \/>La troisi\u00e8me humiliation fut celle de la convocation des forces vives \u00e0 Ouagadougou par le m\u00e9diateur de la CEDEAO. Certains participants, ulc\u00e9r\u00e9s par les attitudes condescendantes de la m\u00e9diation burkinab\u00e9, n\u2019h\u00e9sit\u00e8rent pas \u00e0 dire que le sort du Mali ne saurait \u00eatre d\u00e9cid\u00e9 \u00e0 Ouagadougou mais \u00e0 Bamako. Dr\u00f4le de m\u00e9diation o\u00f9 l\u2019on sentait la prise de position de la CEDEAO en faveur des tenants de l\u2019ordre ancien dont les positions ont \u00e9t\u00e9 pourtant battues en br\u00e8che par l\u2019\u00e9crasante majorit\u00e9 des participants. La d\u00e9claration de Ouagadougou passa sous silence bien de passes d\u2019armes comme le rejet v\u00e9h\u00e9ment de la prolongation du mandat du pr\u00e9sident int\u00e9rimaire et de l\u2019assembl\u00e9e et du&nbsp; projet burkinab\u00e9 de cr\u00e9ation d\u2019un organe de supervision et de suivi de l\u2019accord cadre qui fut per\u00e7ue comme une v\u00e9ritable mise sous tutelle du Mali. Face \u00e0 cette r\u00e9sistance, la m\u00e9diation d\u00e9ploya la ruse voire la duplicit\u00e9. En t\u00e9moignent les non-dits de Ouagadougou qui \u00e9clairent largement les d\u00e9cisions du dernier sommet extraordinaire d\u2019Abidjan.nLe choix du Premier ministre de Transition et la formation en catimini du gouvernement sans consultation aucune des forces vives nationales furent ressentis comme une quatri\u00e8me humiliation. On poussa l\u2019arrogance jusqu\u2019\u00e0 d\u00e9signer le conseiller personnel du m\u00e9diateur comme seul ministre d\u2019Etat charg\u00e9 des affaires \u00e9trang\u00e8res. De nombreux anciens cadres du r\u00e9gime d\u00e9funt de Moussa Traor\u00e9 reprirent du service. Parmi les nouveaux promus, certains trainent des casseroles. Les plus honn\u00eates ignorent les r\u00e9alit\u00e9s du pays qu\u2019ils ont quitt\u00e9 il y a souvent plus de 20 ans pour aller servir des institutions internationales. Quelle est la capacit\u00e9 d\u2019analyse, de lecture et d\u2019interpr\u00e9tation des r\u00e9alit\u00e9s du terrain d\u2019un gouvernement aussi \u00e9tranger \u00e0 son propre peuple ? Que peut-il r\u00e9ellement faire face \u00e0 un tel d\u00e9sastre ? Le moins qu\u2019on puisse dire est que l\u2019actuel Premier Ministre a rat\u00e9 son entr\u00e9e dans l\u2019histoire r\u00e9cente du Mali en allant s\u2019emp\u00eatrer dans les eaux boueuses et croupissantes du pass\u00e9 ? Pourrait-il en \u00e9merger ? Il est permis d\u2019en douter.nLa derni\u00e8re humiliation inflig\u00e9e au peuple malien vint suite au dernier sommet extraordinaire de la CEDEAO qui d\u00e9cida unilat\u00e9ralement de prolonger le mandat du pr\u00e9sident int\u00e9rimaire en violation de la constitution du pays et de fixer la dur\u00e9e de la transition&nbsp; sans concertation aucune avec les principaux int\u00e9ress\u00e9s avec en prime la menace d\u2019une intervention arm\u00e9e pour les soumettre \u00e0 l\u2019ordre promulgu\u00e9 \u00e0 Abidjan.nLa coupe est d\u00e9sormais pleine. L\u2019\u00e9bullition est \u00e0 l\u2019extr\u00eame. Jamais les Maliens n\u2019ont connu autant d\u2019humiliations en un laps de temps aussi court. En t\u00e9moignent les larmes d\u2019amertume d\u2019un vieux malien acteur des ann\u00e9es h\u00e9ro\u00efques de la conqu\u00eate de l\u2019ind\u00e9pendance et de l\u2019exercice de la souverainet\u00e9 nationale qui maudissait le sort pour lui avoir inflig\u00e9 d\u2019assister \u00e0 un moment aussi triste et douloureux de l\u2019histoire du Mali.nMais derri\u00e8re les cendres du Mali actuel en train de sombrer, \u00e9mergent les lueurs d\u2019un Mali nouveau qui pointe \u00e0 l\u2019horizon. Rien ne sera plus comme auparavant. La peur s\u2019est \u00e9vanouie. Les Maliens ne veulent plus laisser leur sort entre les mains d\u2019une bande d\u2019aventuriers aussi bien civils que militaires. Ils ne veulent pas non plus se soumettre au diktat de la CEDEAO agissant sous la dict\u00e9e des puissances ext\u00e9rieures.&nbsp;nLa dynamique populaire en gestation sera comme un rouleau compresseur qui balayera l\u2019ordre ancien. La c\u00e9cit\u00e9 de la classe politique malienne, des dirigeants de la CEDEAO et de leurs parrains occidentaux n\u2019y fera rien. Un nouveau printemps africain est d\u00e9sormais inscrit dans les pages de l\u2019histoire nouvelle du Mali. Sa gestation sera certes difficile et douloureuse. Mais \u00e0 force de vouloir l\u2019endiguer, de la contenir, elle deviendra plus charg\u00e9e de pression, plus violente, plus radicale.nLes politiciens maliens, la CEDEAO et les occidentaux se trompent lourdement en voulant restaurer l\u2019ordre ancien. Il est inacceptable aujourd\u2019hui pour le peuple malien qui veut d\u00e9sormais prendre en main son propre destin. Leurs tentatives de restauration de l\u2019ordre ancien ne fermeront jamais la page des coups d\u2019Etat \u2018populaires\u2019 en Afrique. L\u2019id\u00e9al serait que les peuples se lib\u00e8rent d\u2019eux-m\u00eames par la r\u00e9volution populaire comme celle de 1991 au Mali, trahie et r\u00e9cup\u00e9r\u00e9e par la d\u00e9mocratie des milliardaires.nAujourd\u2019hui ce n\u2019est pas le bulletin de vote qui va r\u00e9gler la question de la d\u00e9mocratie v\u00e9ritable en Afrique mais les luttes populaires de plus en plus fortes, de plus en plus violentes. Plus on tentera de les endiguer, de biaiser, plus elles seront plus d\u00e9termin\u00e9es. Les peuples africains n\u2019ont plus d\u2019autres solutions que de dynamiter les horizons bouch\u00e9s que leur imposent leurs dirigeants corrompus avec la b\u00e9n\u00e9diction des occidentaux.&nbsp;<br \/>Malcolm X&nbsp; a \u00e9t\u00e9 confront\u00e9 au dilemme du choix entre le bulletin de vote et la balle de fusil. Il a fini par comprendre que le bulletin de vote ne l\u2019amenait nulle part. Une balle de fusil mit fin \u00e0 ses illusions. Mao a lui choisi le raccourci historique du \u00ab pouvoir au bout du fusil \u00bb. Les faits semblent lui donner amplement raison.&nbsp;nIl nous faut rejeter la d\u00e9mocratie impos\u00e9e par les menaces, les embargos et les bombes des puissances occidentales comme en Lybie, en C\u00f4te d\u2019Ivoire ou ailleurs en Afrique et partout dans le monde. Ce n\u2019est pas avec des discours et des bulletins de vote que les peuples s\u2019affranchiront r\u00e9ellement mais par leur mobilisation massive, leur engagement pour leur propre salut sans aucune ing\u00e9rence ext\u00e9rieure. Il leur appartient d\u2019inventer leur voie pour \u00e9riger le monde nouveau qui pointe d\u00e9sormais \u00e0 l\u2019horizon. Aucune main ne saurait d\u00e9sormais leur cacher le soleil de la v\u00e9ritable d\u00e9mocratie, celle qui est en train de na\u00eetre de leur col\u00e8re, de leurs frustrations, des impasses de la \u2018d\u00e9mocratie des milliardaires\u2019, une d\u00e9mocratie dirig\u00e9e contre le peuple.n&nbsp;Les Maliens ont compris que les politiciens actuels de tous ordres, partisans de la restauration de l\u2019ordre ancien, leur ont vol\u00e9 leur d\u00e9mocratie si laborieusement conquise en mars 1991. Ils l\u2019ont vid\u00e9e de sa substance et en ont fait un gadget, une sucette, leur sucette. Si le coup d\u2019Etat du 22 Mars les a visiblement d\u00e9rang\u00e9s dans leur projet de festin \u2018d\u00e9mocratique\u2019, il n\u2019a pour l\u2019instant r\u00e9gl\u00e9 aucun probl\u00e8me de fond sauf celui d\u2019inscrire \u00e0 l\u2019ordre du jour leur surgissement sur la sc\u00e8ne de l\u2019histoire que la CEDEAO des Chefs d\u2019Etat veut emp\u00eacher co\u00fbte que co\u00fbte. Le peuple malien aspire \u00e0 saisir la chance historique qui lui a \u00e9t\u00e9 offerte&nbsp; par ce coup d\u2019Etat pour r\u00e9aliser son destin en toute ind\u00e9pendance et en toute libert\u00e9. Il est condamn\u00e9 \u00e0 l\u2019assumer pour r\u00e9inventer son avenir.<\/p>\n<p>Pr Issa N\u2019DIAYE, Bamako 29-04-12<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chute brutale de ATT a mis \u00e0 nu les fondements pourris de la d\u00e9mocratie malienne tant chant\u00e9e \u00e0 l\u2019ext\u00e9rieur. Les populations maliennes l\u2019avaient compris il y a belle lurette. En t\u00e9moignent les taux de participation qui d\u00e9gringolaient d\u2019\u00e9lection en \u00e9lection. De 1991 \u00e0 nos jours, \u00e0 peine 20% des Maliens participent r\u00e9guli\u00e8rement aux \u00e9lections.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[95,85,107],"tags":[],"class_list":["post-1603","post","type-post","status-publish","format-standard","hentry","category-afrikanische-perspektiven","category-events","category-kolonialismus-und-dekolonisierung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr Issa N\u2019Diaye: Mali - une \u2018d\u00e9mocratie\u2019 contre le peuple ! &#8211; AfricAvenir International e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr Issa N\u2019Diaye: Mali - une \u2018d\u00e9mocratie\u2019 contre le peuple ! &#8211; AfricAvenir International e.V.\" \/>\n<meta property=\"og:description\" content=\"La chute brutale de ATT a mis \u00e0 nu les fondements pourris de la d\u00e9mocratie malienne tant chant\u00e9e \u00e0 l\u2019ext\u00e9rieur. Les populations maliennes l\u2019avaient compris il y a belle lurette. En t\u00e9moignent les taux de participation qui d\u00e9gringolaient d\u2019\u00e9lection en \u00e9lection. De 1991 \u00e0 nos jours, \u00e0 peine 20% des Maliens participent r\u00e9guli\u00e8rement aux \u00e9lections.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/\" \/>\n<meta property=\"og:site_name\" content=\"AfricAvenir International e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricAvenir\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-04T22:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T09:40:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"patrpaaa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AfricAvenir\" \/>\n<meta name=\"twitter:site\" content=\"@AfricAvenir\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/\"},\"author\":{\"name\":\"patrpaaa\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#\\\/schema\\\/person\\\/b212b099a4ad75eefb18f17ae282ecfd\"},\"headline\":\"Pr Issa N\u2019Diaye: Mali &#8211; une \u2018d\u00e9mocratie\u2019 contre le peuple !\",\"datePublished\":\"2012-05-04T22:25:00+00:00\",\"dateModified\":\"2023-10-06T09:40:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/\"},\"wordCount\":4867,\"publisher\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#organization\"},\"articleSection\":[\"Afrikanische Perspektiven\",\"Events\",\"Kolonialismus &amp; Dekolonisierung\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/\",\"name\":\"Pr Issa N\u2019Diaye: Mali - une \u2018d\u00e9mocratie\u2019 contre le peuple ! &#8211; AfricAvenir International e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#website\"},\"datePublished\":\"2012-05-04T22:25:00+00:00\",\"dateModified\":\"2023-10-06T09:40:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr Issa N\u2019Diaye: Mali &#8211; une \u2018d\u00e9mocratie\u2019 contre le peuple !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/\",\"name\":\"AfricAvenir International e.V.\",\"description\":\"African Renaissance, Development, International Cooperation And Peace\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#organization\",\"name\":\"AfricAvenir International e.V.\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/AfricAvenir-Logo_transparent.png\",\"contentUrl\":\"https:\\\/\\\/www.africavenir.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/AfricAvenir-Logo_transparent.png\",\"width\":1500,\"height\":1500,\"caption\":\"AfricAvenir International e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AfricAvenir\\\/\",\"https:\\\/\\\/x.com\\\/AfricAvenir\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/en\\\/#\\\/schema\\\/person\\\/b212b099a4ad75eefb18f17ae282ecfd\",\"name\":\"patrpaaa\",\"sameAs\":[\"https:\\\/\\\/www.africavenir.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr Issa N\u2019Diaye: Mali - une \u2018d\u00e9mocratie\u2019 contre le peuple ! &#8211; AfricAvenir International e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/","og_locale":"en_US","og_type":"article","og_title":"Pr Issa N\u2019Diaye: Mali - une \u2018d\u00e9mocratie\u2019 contre le peuple ! &#8211; AfricAvenir International e.V.","og_description":"La chute brutale de ATT a mis \u00e0 nu les fondements pourris de la d\u00e9mocratie malienne tant chant\u00e9e \u00e0 l\u2019ext\u00e9rieur. Les populations maliennes l\u2019avaient compris il y a belle lurette. En t\u00e9moignent les taux de participation qui d\u00e9gringolaient d\u2019\u00e9lection en \u00e9lection. De 1991 \u00e0 nos jours, \u00e0 peine 20% des Maliens participent r\u00e9guli\u00e8rement aux \u00e9lections.&hellip;","og_url":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/","og_site_name":"AfricAvenir International e.V.","article_publisher":"https:\/\/www.facebook.com\/AfricAvenir\/","article_published_time":"2012-05-04T22:25:00+00:00","article_modified_time":"2023-10-06T09:40:56+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png","type":"image\/png"}],"author":"patrpaaa","twitter_card":"summary_large_image","twitter_creator":"@AfricAvenir","twitter_site":"@AfricAvenir","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/#article","isPartOf":{"@id":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/"},"author":{"name":"patrpaaa","@id":"https:\/\/www.africavenir.org\/en\/#\/schema\/person\/b212b099a4ad75eefb18f17ae282ecfd"},"headline":"Pr Issa N\u2019Diaye: Mali &#8211; une \u2018d\u00e9mocratie\u2019 contre le peuple !","datePublished":"2012-05-04T22:25:00+00:00","dateModified":"2023-10-06T09:40:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/"},"wordCount":4867,"publisher":{"@id":"https:\/\/www.africavenir.org\/en\/#organization"},"articleSection":["Afrikanische Perspektiven","Events","Kolonialismus &amp; Dekolonisierung"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/","url":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/","name":"Pr Issa N\u2019Diaye: Mali - une \u2018d\u00e9mocratie\u2019 contre le peuple ! &#8211; AfricAvenir International e.V.","isPartOf":{"@id":"https:\/\/www.africavenir.org\/en\/#website"},"datePublished":"2012-05-04T22:25:00+00:00","dateModified":"2023-10-06T09:40:56+00:00","breadcrumb":{"@id":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.africavenir.org\/en\/pr-issa-ndiaye-mali-une-democratie-contre-le-peuple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.africavenir.org\/en\/"},{"@type":"ListItem","position":2,"name":"Pr Issa N\u2019Diaye: Mali &#8211; une \u2018d\u00e9mocratie\u2019 contre le peuple !"}]},{"@type":"WebSite","@id":"https:\/\/www.africavenir.org\/en\/#website","url":"https:\/\/www.africavenir.org\/en\/","name":"AfricAvenir International e.V.","description":"African Renaissance, Development, International Cooperation And Peace","publisher":{"@id":"https:\/\/www.africavenir.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africavenir.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.africavenir.org\/en\/#organization","name":"AfricAvenir International e.V.","url":"https:\/\/www.africavenir.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.africavenir.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png","contentUrl":"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png","width":1500,"height":1500,"caption":"AfricAvenir International e.V."},"image":{"@id":"https:\/\/www.africavenir.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AfricAvenir\/","https:\/\/x.com\/AfricAvenir"]},{"@type":"Person","@id":"https:\/\/www.africavenir.org\/en\/#\/schema\/person\/b212b099a4ad75eefb18f17ae282ecfd","name":"patrpaaa","sameAs":["https:\/\/www.africavenir.org"]}]}},"_links":{"self":[{"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/posts\/1603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/comments?post=1603"}],"version-history":[{"count":1,"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/posts\/1603\/revisions"}],"predecessor-version":[{"id":1808,"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/posts\/1603\/revisions\/1808"}],"wp:attachment":[{"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/media?parent=1603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/categories?post=1603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africavenir.org\/en\/wp-json\/wp\/v2\/tags?post=1603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}