{"id":462,"date":"2016-06-21T11:17:00","date_gmt":"2016-06-21T09:17:00","guid":{"rendered":"https:\/\/www.africavenir.com\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/"},"modified":"2023-10-06T11:41:46","modified_gmt":"2023-10-06T09:41:46","slug":"bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs","status":"publish","type":"post","link":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/","title":{"rendered":"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs"},"content":{"rendered":"<p>Friedenslauf hei\u00dft nicht nur laufen f\u00fcr den Frieden. Die Sch\u00fcler_innen werden auch zu Schrittmacher_innen f\u00fcr den Frieden, indem sie sich mit gewaltfreien Alternativen im Umgang mit Konflikten auseinandersetzen.nFrieden und gewaltfreie Konfliktl\u00f6sung m\u00fcssen wir immer wieder erlernen \u2013 jung wie alt. Im Rahmen des Berliner Friedenslaufs bietet daher das Forum Ziviler Friedensdienst (forumZFD) ein Bildungsprogramm an, welche teilnehmende Schulen kostenfrei vor und nach dem Lauf nutzen k\u00f6nnen, um verschiedene Themen der konkreten Friedensarbeit und des Globalen Lernens kennen zu lernen. F\u00fcr dieses Bildungsprogramm stehen kompetente Referent_innen zur Verf\u00fcgung, die gerne in Ihre Schule kommen. nZudem bietet das forumZFD ein umfangreiches Bildungsmaterial an, welches zu diversen Themen von Lehrer_innen vor und nach dem Friedenslauf selbstst\u00e4ndig genutzt werden kann.n<link http:\/\/www.run4peace.eu\/berlin\/frieden-lernen - - \"\u00d6ffnet externen Link in neuem Fenster\">Mehr Infos<\/link>\n","protected":false},"excerpt":{"rendered":"<p>Friedenslauf hei\u00dft nicht nur laufen f\u00fcr den Frieden. Die Sch\u00fcler_innen werden auch zu Schrittmacher_innen f\u00fcr den Frieden, indem sie sich mit gewaltfreien Alternativen im Umgang mit Konflikten auseinandersetzen.nFrieden und gewaltfreie Konfliktl\u00f6sung m\u00fcssen wir immer wieder erlernen \u2013 jung wie alt. Im Rahmen des Berliner Friedenslaufs bietet daher das Forum Ziviler Friedensdienst (forumZFD) ein Bildungsprogramm an,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85,107],"tags":[],"class_list":["post-462","post","type-post","status-publish","format-standard","hentry","category-events","category-kolonialismus-und-dekolonisierung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs &#8211; AfricAvenir International e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs &#8211; AfricAvenir International e.V.\" \/>\n<meta property=\"og:description\" content=\"Friedenslauf hei\u00dft nicht nur laufen f\u00fcr den Frieden. Die Sch\u00fcler_innen werden auch zu Schrittmacher_innen f\u00fcr den Frieden, indem sie sich mit gewaltfreien Alternativen im Umgang mit Konflikten auseinandersetzen.nFrieden und gewaltfreie Konfliktl\u00f6sung m\u00fcssen wir immer wieder erlernen \u2013 jung wie alt. Im Rahmen des Berliner Friedenslaufs bietet daher das Forum Ziviler Friedensdienst (forumZFD) ein Bildungsprogramm an,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/\" \/>\n<meta property=\"og:site_name\" content=\"AfricAvenir International e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricAvenir\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-21T09:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T09:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"patrpaaa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AfricAvenir\" \/>\n<meta name=\"twitter:site\" content=\"@AfricAvenir\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/\"},\"author\":{\"name\":\"patrpaaa\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#\\\/schema\\\/person\\\/b212b099a4ad75eefb18f17ae282ecfd\"},\"headline\":\"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs\",\"datePublished\":\"2016-06-21T09:17:00+00:00\",\"dateModified\":\"2023-10-06T09:41:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/\"},\"wordCount\":138,\"publisher\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#organization\"},\"articleSection\":[\"Events\",\"Kolonialismus &amp; Dekolonisierung\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/\",\"name\":\"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs &#8211; AfricAvenir International e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#website\"},\"datePublished\":\"2016-06-21T09:17:00+00:00\",\"dateModified\":\"2023-10-06T09:41:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/\",\"name\":\"AfricAvenir International e.V.\",\"description\":\"African Renaissance, Development, International Cooperation And Peace\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#organization\",\"name\":\"AfricAvenir International e.V.\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.africavenir.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/AfricAvenir-Logo_transparent.png\",\"contentUrl\":\"https:\\\/\\\/www.africavenir.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/AfricAvenir-Logo_transparent.png\",\"width\":1500,\"height\":1500,\"caption\":\"AfricAvenir International e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AfricAvenir\\\/\",\"https:\\\/\\\/x.com\\\/AfricAvenir\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.africavenir.org\\\/fr\\\/#\\\/schema\\\/person\\\/b212b099a4ad75eefb18f17ae282ecfd\",\"name\":\"patrpaaa\",\"sameAs\":[\"https:\\\/\\\/www.africavenir.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs &#8211; AfricAvenir International e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/","og_locale":"fr_FR","og_type":"article","og_title":"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs &#8211; AfricAvenir International e.V.","og_description":"Friedenslauf hei\u00dft nicht nur laufen f\u00fcr den Frieden. Die Sch\u00fcler_innen werden auch zu Schrittmacher_innen f\u00fcr den Frieden, indem sie sich mit gewaltfreien Alternativen im Umgang mit Konflikten auseinandersetzen.nFrieden und gewaltfreie Konfliktl\u00f6sung m\u00fcssen wir immer wieder erlernen \u2013 jung wie alt. Im Rahmen des Berliner Friedenslaufs bietet daher das Forum Ziviler Friedensdienst (forumZFD) ein Bildungsprogramm an,&hellip;","og_url":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/","og_site_name":"AfricAvenir International e.V.","article_publisher":"https:\/\/www.facebook.com\/AfricAvenir\/","article_published_time":"2016-06-21T09:17:00+00:00","article_modified_time":"2023-10-06T09:41:46+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png","type":"image\/png"}],"author":"patrpaaa","twitter_card":"summary_large_image","twitter_creator":"@AfricAvenir","twitter_site":"@AfricAvenir","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/#article","isPartOf":{"@id":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/"},"author":{"name":"patrpaaa","@id":"https:\/\/www.africavenir.org\/fr\/#\/schema\/person\/b212b099a4ad75eefb18f17ae282ecfd"},"headline":"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs","datePublished":"2016-06-21T09:17:00+00:00","dateModified":"2023-10-06T09:41:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/"},"wordCount":138,"publisher":{"@id":"https:\/\/www.africavenir.org\/fr\/#organization"},"articleSection":["Events","Kolonialismus &amp; Dekolonisierung"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/","url":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/","name":"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs &#8211; AfricAvenir International e.V.","isPartOf":{"@id":"https:\/\/www.africavenir.org\/fr\/#website"},"datePublished":"2016-06-21T09:17:00+00:00","dateModified":"2023-10-06T09:41:46+00:00","breadcrumb":{"@id":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.africavenir.org\/fr\/bildungsprogramm-im-rahmen-des-11-berliner-friedenslaufs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.africavenir.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Bildungsprogramm im Rahmen des 11. Berliner Friedenslaufs"}]},{"@type":"WebSite","@id":"https:\/\/www.africavenir.org\/fr\/#website","url":"https:\/\/www.africavenir.org\/fr\/","name":"AfricAvenir International e.V.","description":"African Renaissance, Development, International Cooperation And Peace","publisher":{"@id":"https:\/\/www.africavenir.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africavenir.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.africavenir.org\/fr\/#organization","name":"AfricAvenir International e.V.","url":"https:\/\/www.africavenir.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africavenir.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png","contentUrl":"https:\/\/www.africavenir.org\/wp-content\/uploads\/2023\/08\/AfricAvenir-Logo_transparent.png","width":1500,"height":1500,"caption":"AfricAvenir International e.V."},"image":{"@id":"https:\/\/www.africavenir.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AfricAvenir\/","https:\/\/x.com\/AfricAvenir"]},{"@type":"Person","@id":"https:\/\/www.africavenir.org\/fr\/#\/schema\/person\/b212b099a4ad75eefb18f17ae282ecfd","name":"patrpaaa","sameAs":["https:\/\/www.africavenir.org"]}]}},"_links":{"self":[{"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/posts\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/comments?post=462"}],"version-history":[{"count":1,"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/posts\/462\/revisions"}],"predecessor-version":[{"id":562,"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/posts\/462\/revisions\/562"}],"wp:attachment":[{"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/media?parent=462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/categories?post=462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africavenir.org\/fr\/wp-json\/wp\/v2\/tags?post=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}